{"id":19801,"date":"2023-11-25T18:26:18","date_gmt":"2023-11-25T17:26:18","guid":{"rendered":"https:\/\/accademiamugnano.it\/?post_type=product&#038;p=19801"},"modified":"2026-05-22T09:48:37","modified_gmt":"2026-05-22T07:48:37","slug":"pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino","status":"publish","type":"product","link":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/","title":{"rendered":"Pentola antiaderente 2 maniglie con coperchio in vetro &#8211; Rubino"},"content":{"rendered":"<p><b>Rubino Collection<\/b><span style=\"font-weight: 400;\"> \u00e8 la linea pensata per accompagnare ogni giorno chi cerca funzionalit\u00e0, stile e convenienza. Grazie all\u2019ampia gamma di prodotti, \u00e8 perfetta per affrontare tutte le preparazioni della cucina quotidiana.<\/span><\/p>\n<h6><\/h6>\n<p><span style=\"font-weight: 400;\">Il rivestimento interno <\/span><b>AM Salus Hard System<\/b><span style=\"font-weight: 400;\"> garantisce resistenza all\u2019usura, elevata antiaderenza e una cucina pi\u00f9 sana e sicura, nel rispetto dell\u2019ambiente e della salute.<\/span><\/p>\n<h6><\/h6>\n<p><span style=\"font-weight: 400;\">Il corpo in alluminio assicura una buona distribuzione del calore, mentre il fondo rettificato antiscivolo offre stabilit\u00e0 e uniformit\u00e0 di cottura su tutte le superfici tranne l\u2019induzione.<\/span><\/p>\n<h6><\/h6>\n<p><span style=\"font-weight: 400;\">Il design \u00e8 completato da manici ergonomici in bakelite rossa con tampografia, atermici e resistenti, e dal rivestimento esterno in lacca siliconica rosso metallizzato, per un\u2019estetica calda e decisa che dona carattere alla cucina.<\/span><\/p>\n<h6><\/h6>\n<p><b>Rubino<\/b><span style=\"font-weight: 400;\"> \u00e8 la scelta perfetta per chi desidera coniugare <\/span><b>qualit\u00e0, durata ed eleganza<\/b><span style=\"font-weight: 400;\">, senza rinunciare alla semplicit\u00e0 d\u2019uso.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pentola antiaderente 2 maniglie coperchio in vetro &#8211; Rubino<\/p>\n","protected":false},"featured_media":20586,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[579,609],"product_tag":[635,173],"class_list":["post-19801","product","type-product","status-publish","has-post-thumbnail","product_cat-pentole","product_cat-linea-rubino","product_tag-coperchio-in-vetro","product_tag-non-induzione","pa_tipologia-cottura-elettrico","pa_tipologia-cottura-gas","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pentola antiaderente 2 maniglie con coperchio in vetro - Rubino - Accademia Mugnano<\/title>\n<meta name=\"description\" content=\"Pentola in alluminio puro al 99,5% con rivestimento interno antiaderente a 5 strati, rivestimento esterno rosso e coperchio in vetro - Rubino\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pentola antiaderente 2 maniglie con coperchio in vetro - Rubino - Accademia Mugnano\" \/>\n<meta property=\"og:description\" content=\"Pentola in alluminio puro al 99,5% con rivestimento interno antiaderente a 5 strati, rivestimento esterno rosso e coperchio in vetro - Rubino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/\" \/>\n<meta property=\"og:site_name\" content=\"Accademia Mugnano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T07:48:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/RUPNTCV20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/\",\"name\":\"Pentola antiaderente 2 maniglie con coperchio in vetro - Rubino - Accademia Mugnano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/RUPNTCV20.jpg\",\"datePublished\":\"2023-11-25T17:26:18+00:00\",\"dateModified\":\"2026-05-22T07:48:37+00:00\",\"description\":\"Pentola in alluminio puro al 99,5% con rivestimento interno antiaderente a 5 strati, rivestimento esterno rosso e coperchio in vetro - Rubino\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/RUPNTCV20.jpg\",\"contentUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/RUPNTCV20.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti OLD\",\"item\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/?page_id=21525\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pentola antiaderente 2 maniglie con coperchio in vetro &#8211; Rubino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\",\"name\":\"Accademia Mugnano\",\"description\":\"Pentole e padelle made in Italy antiaderenti in alluminio. Cucina sano, cucina italiano.\",\"publisher\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#organization\",\"name\":\"Accademia Mugnano\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Accademia-Mugnano.png\",\"contentUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Accademia-Mugnano.png\",\"width\":1824,\"height\":585,\"caption\":\"Accademia Mugnano\"},\"image\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pentola antiaderente 2 maniglie con coperchio in vetro - Rubino - Accademia Mugnano","description":"Pentola in alluminio puro al 99,5% con rivestimento interno antiaderente a 5 strati, rivestimento esterno rosso e coperchio in vetro - Rubino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/","og_locale":"fr_FR","og_type":"article","og_title":"Pentola antiaderente 2 maniglie con coperchio in vetro - Rubino - Accademia Mugnano","og_description":"Pentola in alluminio puro al 99,5% con rivestimento interno antiaderente a 5 strati, rivestimento esterno rosso e coperchio in vetro - Rubino","og_url":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/","og_site_name":"Accademia Mugnano","article_modified_time":"2026-05-22T07:48:37+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/RUPNTCV20.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/","url":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/","name":"Pentola antiaderente 2 maniglie con coperchio in vetro - Rubino - Accademia Mugnano","isPartOf":{"@id":"https:\/\/accademiamugnano.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/#primaryimage"},"image":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/#primaryimage"},"thumbnailUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/RUPNTCV20.jpg","datePublished":"2023-11-25T17:26:18+00:00","dateModified":"2026-05-22T07:48:37+00:00","description":"Pentola in alluminio puro al 99,5% con rivestimento interno antiaderente a 5 strati, rivestimento esterno rosso e coperchio in vetro - Rubino","breadcrumb":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/#primaryimage","url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/RUPNTCV20.jpg","contentUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/RUPNTCV20.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/pentola-antiaderente-2-maniglie-con-coperchio-in-vetro-rubino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accademiamugnano.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti OLD","item":"https:\/\/accademiamugnano.it\/fr\/?page_id=21525"},{"@type":"ListItem","position":3,"name":"Pentola antiaderente 2 maniglie con coperchio in vetro &#8211; Rubino"}]},{"@type":"WebSite","@id":"https:\/\/accademiamugnano.it\/fr\/#website","url":"https:\/\/accademiamugnano.it\/fr\/","name":"Accademia Mugnano","description":"Pentole e padelle made in Italy antiaderenti in alluminio. Cucina sano, cucina italiano.","publisher":{"@id":"https:\/\/accademiamugnano.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accademiamugnano.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/accademiamugnano.it\/fr\/#organization","name":"Accademia Mugnano","url":"https:\/\/accademiamugnano.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/accademiamugnano.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/09\/Accademia-Mugnano.png","contentUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/09\/Accademia-Mugnano.png","width":1824,"height":585,"caption":"Accademia Mugnano"},"image":{"@id":"https:\/\/accademiamugnano.it\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product\/19801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/media\/20586"}],"wp:attachment":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/media?parent=19801"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_brand?post=19801"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_cat?post=19801"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_tag?post=19801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}