{"id":19531,"date":"2023-11-23T17:51:10","date_gmt":"2023-11-23T16:51:10","guid":{"rendered":"https:\/\/accademiamugnano.it\/?post_type=product&#038;p=19531"},"modified":"2026-05-26T14:41:55","modified_gmt":"2026-05-26T12:41:55","slug":"teglia-quadra-fuoco-idee","status":"publish","type":"product","link":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/","title":{"rendered":"Teglia quadra 35&#215;35 cm &#8211; Fuoco &#038; Idee"},"content":{"rendered":"<p>Una fantastica teglia antiaderente dalle grandi dimensioni per poter cucinare il piatto preferito dagli italiani: la Lasagna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teglia per lasagna quadra 35 x 35 cm &#8211; Fuoco &amp; Idee<\/p>\n","protected":false},"featured_media":19979,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[602,584],"product_tag":[865,1026],"class_list":["post-19531","product","type-product","status-publish","has-post-thumbnail","product_cat-linea-fuoco-idee","product_cat-teglie","product_tag-in-forno","product_tag-quadrata","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teglia quadra 35x35 cm - Fuoco &amp; Idee - Accademia Mugnano<\/title>\n<meta name=\"description\" content=\"Teglia da forno quadrata in alluminio antiaderente ideale per la preparazione di piatti al forno come la lasagna - Fuoco &amp; Idee\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teglia quadra 35x35 cm - Fuoco &amp; Idee - Accademia Mugnano\" \/>\n<meta property=\"og:description\" content=\"Teglia da forno quadrata in alluminio antiaderente ideale per la preparazione di piatti al forno come la lasagna - Fuoco &amp; Idee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/\" \/>\n<meta property=\"og:site_name\" content=\"Accademia Mugnano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T12:41:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/FITGLQ35_q.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/\",\"name\":\"Teglia quadra 35x35 cm - Fuoco & Idee - Accademia Mugnano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/FITGLQ35_q.jpg\",\"datePublished\":\"2023-11-23T16:51:10+00:00\",\"dateModified\":\"2026-05-26T12:41:55+00:00\",\"description\":\"Teglia da forno quadrata in alluminio antiaderente ideale per la preparazione di piatti al forno come la lasagna - Fuoco & Idee\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/FITGLQ35_q.jpg\",\"contentUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/FITGLQ35_q.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/teglia-quadra-fuoco-idee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti OLD\",\"item\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/?page_id=21525\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Teglia quadra 35&#215;35 cm &#8211; Fuoco &#038; Idee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\",\"name\":\"Accademia Mugnano\",\"description\":\"Pentole e padelle made in Italy antiaderenti in alluminio. Cucina sano, cucina italiano.\",\"publisher\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#organization\",\"name\":\"Accademia Mugnano\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Accademia-Mugnano.png\",\"contentUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Accademia-Mugnano.png\",\"width\":1824,\"height\":585,\"caption\":\"Accademia Mugnano\"},\"image\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teglia quadra 35x35 cm - Fuoco & Idee - Accademia Mugnano","description":"Teglia da forno quadrata in alluminio antiaderente ideale per la preparazione di piatti al forno come la lasagna - Fuoco & Idee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/","og_locale":"fr_FR","og_type":"article","og_title":"Teglia quadra 35x35 cm - Fuoco & Idee - Accademia Mugnano","og_description":"Teglia da forno quadrata in alluminio antiaderente ideale per la preparazione di piatti al forno come la lasagna - Fuoco & Idee","og_url":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/","og_site_name":"Accademia Mugnano","article_modified_time":"2026-05-26T12:41:55+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/FITGLQ35_q.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/","url":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/","name":"Teglia quadra 35x35 cm - Fuoco & Idee - Accademia Mugnano","isPartOf":{"@id":"https:\/\/accademiamugnano.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/#primaryimage"},"image":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/#primaryimage"},"thumbnailUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/FITGLQ35_q.jpg","datePublished":"2023-11-23T16:51:10+00:00","dateModified":"2026-05-26T12:41:55+00:00","description":"Teglia da forno quadrata in alluminio antiaderente ideale per la preparazione di piatti al forno come la lasagna - Fuoco & Idee","breadcrumb":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/#primaryimage","url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/FITGLQ35_q.jpg","contentUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/FITGLQ35_q.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/teglia-quadra-fuoco-idee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accademiamugnano.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti OLD","item":"https:\/\/accademiamugnano.it\/fr\/?page_id=21525"},{"@type":"ListItem","position":3,"name":"Teglia quadra 35&#215;35 cm &#8211; Fuoco &#038; Idee"}]},{"@type":"WebSite","@id":"https:\/\/accademiamugnano.it\/fr\/#website","url":"https:\/\/accademiamugnano.it\/fr\/","name":"Accademia Mugnano","description":"Pentole e padelle made in Italy antiaderenti in alluminio. Cucina sano, cucina italiano.","publisher":{"@id":"https:\/\/accademiamugnano.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accademiamugnano.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/accademiamugnano.it\/fr\/#organization","name":"Accademia Mugnano","url":"https:\/\/accademiamugnano.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/accademiamugnano.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/09\/Accademia-Mugnano.png","contentUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/09\/Accademia-Mugnano.png","width":1824,"height":585,"caption":"Accademia Mugnano"},"image":{"@id":"https:\/\/accademiamugnano.it\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product\/19531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/media?parent=19531"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_brand?post=19531"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_cat?post=19531"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_tag?post=19531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}