{"id":19444,"date":"2023-11-23T17:50:00","date_gmt":"2023-11-23T16:50:00","guid":{"rendered":"https:\/\/accademiamugnano.it\/?post_type=product&#038;p=19444"},"modified":"2026-07-01T16:01:36","modified_gmt":"2026-07-01T14:01:36","slug":"crepiere-antiaderente-effetto-pietra-cuore-di-pietra","status":"publish","type":"product","link":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/","title":{"rendered":"Crepiere antiaderente effetto pietra &#8211; Cuore di Pietra"},"content":{"rendered":"<p><strong>Cuore di pietra<\/strong> \u00e8 una linea di padelle e pentole in alluminio forgiato ad alto spessore, progettata per offrire robustezza, efficienza e durata nel tempo. Ideale per l\u2019uso quotidiano, unisce tecnologia e design per accompagnarti in cucina con stile e affidabilit\u00e0.<\/p>\n<h6><\/h6>\n<p>La gamma comprende una vasta scelta di utensili di diverse dimensioni: padelle, casseruole, tegami, wok, saltapasta, crepiere, bistecchiere, pentolini bollilatte e teglie. Qualunque sia la tua ricetta, trovi sempre la forma giusta per cucinarla al meglio.<\/p>\n<h6><\/h6>\n<p>Il rivestimento\u00a0<strong>AM Mineral Stone<\/strong>\u00a0effetto pietra, garantisce una superficie altamente antiaderente, ideale per cucinare senza l\u2019aggiunta di olio o grassi, mantenendo intatti sapori e propriet\u00e0 nutritive. Tutti i prodotti sono disponibili\u00a0<strong>sia in versione per induzione che per fuochi tradizionali<\/strong>, per adattarsi a ogni cucina e a ogni esigenza.<\/p>\n<h6><\/h6>\n<p>Prodotte interamente in Italia, le pentole\u00a0<strong>Cuore di Pietra<\/strong>\u00a0sono sane, sicure ed ecologiche. Il corpo in alluminio assicura una diffusione uniforme del calore, mentre manici e maniglie soft touch, dal design ergonomico e finitura solida, completano una linea progettata per resistere nel tempo ed affrontare ogni sfida in cucina!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crepiere antiaderente effetto pietra &#8211; Cuore di Pietra<\/p>\n","protected":false},"featured_media":62830,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[587,607,575],"product_tag":[645,734,152,173],"class_list":["post-19444","product","type-product","status-publish","has-post-thumbnail","product_cat-crepiere","product_cat-linea-cuore-di-pietra","product_cat-induzione","product_tag-dolci","product_tag-effetto-pietra","product_tag-induzione","product_tag-non-induzione","pa_tipologia-cottura-elettrico","pa_tipologia-cottura-gas","pa_tipologia-cottura-induzione","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crepiere antiaderente effetto pietra - Cuore di Pietra - Accademia Mugnano<\/title>\n<meta name=\"description\" content=\"Crepiere in alluminio forgiato antiaderente rivestimento effetto pietra rinforzato con particelle minerali per una maggiore resistenza - Cuore di Pietra\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crepiere antiaderente effetto pietra - Cuore di Pietra - Accademia Mugnano\" \/>\n<meta property=\"og:description\" content=\"Crepiere in alluminio forgiato antiaderente rivestimento effetto pietra rinforzato con particelle minerali per una maggiore resistenza - Cuore di Pietra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/\" \/>\n<meta property=\"og:site_name\" content=\"Accademia Mugnano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T14:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/CPCRP30I.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/\",\"name\":\"Crepiere antiaderente effetto pietra - Cuore di Pietra - Accademia Mugnano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/CPCRP30I.jpg\",\"datePublished\":\"2023-11-23T16:50:00+00:00\",\"dateModified\":\"2026-07-01T14:01:36+00:00\",\"description\":\"Crepiere in alluminio forgiato antiaderente rivestimento effetto pietra rinforzato con particelle minerali per una maggiore resistenza - Cuore di Pietra\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/CPCRP30I.jpg\",\"contentUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/CPCRP30I.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/prodotto\\\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti OLD\",\"item\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/?page_id=21525\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crepiere antiaderente effetto pietra &#8211; Cuore di Pietra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\",\"name\":\"Accademia Mugnano\",\"description\":\"Pentole e padelle made in Italy antiaderenti in alluminio. Cucina sano, cucina italiano.\",\"publisher\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#organization\",\"name\":\"Accademia Mugnano\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Accademia-Mugnano.png\",\"contentUrl\":\"https:\\\/\\\/accademiamugnano.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Accademia-Mugnano.png\",\"width\":1824,\"height\":585,\"caption\":\"Accademia Mugnano\"},\"image\":{\"@id\":\"https:\\\/\\\/accademiamugnano.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crepiere antiaderente effetto pietra - Cuore di Pietra - Accademia Mugnano","description":"Crepiere in alluminio forgiato antiaderente rivestimento effetto pietra rinforzato con particelle minerali per una maggiore resistenza - Cuore di Pietra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/","og_locale":"fr_FR","og_type":"article","og_title":"Crepiere antiaderente effetto pietra - Cuore di Pietra - Accademia Mugnano","og_description":"Crepiere in alluminio forgiato antiaderente rivestimento effetto pietra rinforzato con particelle minerali per una maggiore resistenza - Cuore di Pietra","og_url":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/","og_site_name":"Accademia Mugnano","article_modified_time":"2026-07-01T14:01:36+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/CPCRP30I.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/","url":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/","name":"Crepiere antiaderente effetto pietra - Cuore di Pietra - Accademia Mugnano","isPartOf":{"@id":"https:\/\/accademiamugnano.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/#primaryimage"},"image":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/#primaryimage"},"thumbnailUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/CPCRP30I.jpg","datePublished":"2023-11-23T16:50:00+00:00","dateModified":"2026-07-01T14:01:36+00:00","description":"Crepiere in alluminio forgiato antiaderente rivestimento effetto pietra rinforzato con particelle minerali per una maggiore resistenza - Cuore di Pietra","breadcrumb":{"@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/#primaryimage","url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/CPCRP30I.jpg","contentUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/11\/CPCRP30I.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/accademiamugnano.it\/fr\/prodotto\/crepiere-antiaderente-effetto-pietra-cuore-di-pietra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accademiamugnano.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti OLD","item":"https:\/\/accademiamugnano.it\/fr\/?page_id=21525"},{"@type":"ListItem","position":3,"name":"Crepiere antiaderente effetto pietra &#8211; Cuore di Pietra"}]},{"@type":"WebSite","@id":"https:\/\/accademiamugnano.it\/fr\/#website","url":"https:\/\/accademiamugnano.it\/fr\/","name":"Accademia Mugnano","description":"Pentole e padelle made in Italy antiaderenti in alluminio. Cucina sano, cucina italiano.","publisher":{"@id":"https:\/\/accademiamugnano.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accademiamugnano.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/accademiamugnano.it\/fr\/#organization","name":"Accademia Mugnano","url":"https:\/\/accademiamugnano.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/accademiamugnano.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/09\/Accademia-Mugnano.png","contentUrl":"https:\/\/accademiamugnano.it\/wp-content\/uploads\/2023\/09\/Accademia-Mugnano.png","width":1824,"height":585,"caption":"Accademia Mugnano"},"image":{"@id":"https:\/\/accademiamugnano.it\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product\/19444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/media\/62830"}],"wp:attachment":[{"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/media?parent=19444"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_brand?post=19444"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_cat?post=19444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/accademiamugnano.it\/fr\/wp-json\/wp\/v2\/product_tag?post=19444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}